{"id":2221,"date":"2012-07-12T10:11:49","date_gmt":"2012-07-12T08:11:49","guid":{"rendered":"http:\/\/www.tagungshotels-online.de\/blog\/?p=2221"},"modified":"2012-07-12T10:12:21","modified_gmt":"2012-07-12T08:12:21","slug":"dorint-golf-spa-windhagensiebengebirge-golfen-reitsport-und-wellness-sind-die-trumpfe","status":"publish","type":"post","link":"https:\/\/www.tagungshotels-online.de\/blog\/2012\/07\/dorint-golf-spa-windhagensiebengebirge-golfen-reitsport-und-wellness-sind-die-trumpfe\/","title":{"rendered":"Dorint Golf &#038; Spa Windhagen\/Siebengebirge: Golfen, Reitsport und Wellness sind die Tr\u00fcmpfe"},"content":{"rendered":"<p><em>Neuer Hoteldirektor des Dorint Golf &amp; Spa Windhagen\/Siebengebirge ist Rainer Sch\u00e4fer. Er will das Haus wieder als ein Hotel f\u00fcr Pferdefreunde etablieren.<\/em><\/p>\n<p><strong>Windhagen\/K\u00f6ln<\/strong> \u2013 Kooperationen mit dem Reitsport, Engagement f\u00fcr Servicequalit\u00e4t und engere Kontakte zur Region: Mit viel Elan ist Rainer Sch\u00e4fer aus den Startbl\u00f6cken gekommen. Der 47-J\u00e4hrige ist neuer Hoteldirektor des Dorint Golf &amp; Spa Windhagen\/Siebengebirge. Damit tritt er die Nachfolge von Adriano Cremonese an, der das Hotel acht Jahre erfolgreich gef\u00fchrt hat und nun in den Ruhestand gegangen ist. In seiner Funktion als Hoteldirektor will Sch\u00e4fer neue Akzente im Hotel setzen. \u201eIch will das Haus Schritt f\u00fcr Schritt nach vorne bringen. Die Qualit\u00e4t unserer Dienstleistung steht dabei im Vordergrund.\u201c\u00a0 <!--more--><\/p>\n<p>Einen wichtigen Schritt auf dem Weg dorthin hat Sch\u00e4fer und sein Team bereits mit der Zusammenarbeit mit dem Birkengest\u00fct Laura erreicht. Gemeinsam bieten sie als \u201eDorint Gest\u00fct Waldbrunnen\u201c Reitunterricht, Ausritte in unber\u00fchrter Natur und in Verbindung mit den Pferden F\u00fchrungsseminare und Teamtrainings an. \u201eMit der einzigartigen Kombination aus Golfen, Reitsport und Wellness heben wir uns ab. In Deutschland gibt es kein weiteres Hotel in der Gr\u00f6\u00dfe mit 125 Zimmern und diesem vielf\u00e4ltigen Angebot\u201c, sagt Sch\u00e4fer.<\/p>\n<p><strong>\u201eUnsere G\u00e4ste haben Anspruch auf allerbeste Qualit\u00e4t\u201c<\/strong><br \/>\nDass sich die G\u00e4ste wohlf\u00fchlen, daf\u00fcr garantieren die Mitarbeiter des Dorint Golf &amp; Spa Windhagen\/Siebengebirge. Das Hotel hat die Zertifizierung ServiceQualit\u00e4t Deutschland erhalten. Die Initiative ServiceQ wurde ins Leben gerufen, um das Niveau der Dienstleistungsunternehmen zu heben. Der Schl\u00fcssel zum Erfolg: Betriebe nehmen ihre Dienstleistung konsequent aus der Kunden-Perspektive wahr. So werden Defizite leichter festgestellt, behoben und verbessert. \u201eUnsere G\u00e4ste haben Anspruch auf allerbeste Servicequalit\u00e4t. Denn nur zufriedene G\u00e4ste kommen wieder. Deshalb sind wir auf die W\u00fcnsche und Bed\u00fcrfnisse unserer G\u00e4ste sensibilisiert\u201c, so der neue Hoteldirektor.<\/p>\n<p>Sch\u00e4fer sieht das Hotel als festen Bestandteil der Region. Hier will er sich noch mehr einbringen und weitere Kontakte kn\u00fcpfen. \u201eWir wollen das MICE Hotel der Region werden\u201c, hat er sich zum Ziel gesetzt. MICE steht f\u00fcr die Tagungswirtschaft, bestehend aus Meetings, Incentives, Kongresse und Events. \u201eDurch unsere Veranstaltungskapazit\u00e4ten haben wir bereits einen gro\u00dfen Anteil am Tagungsgesch\u00e4ft. Trotzdem k\u00f6nnen wir das noch ausbauen.\u201c<\/p>\n<p>Neben einem eingespielten Hotelteam baut Rainer Sch\u00e4fer auch auf sein eigenes Fundament mit jahrzehntelanger Erfahrung in der Hotelbranche. Die vergangenen f\u00fcnf Jahre war der Familienvater Leiter Controlling, Berichtswesen und IT in der Hauptverwaltung der Dorint Hotels &amp; Resorts in K\u00f6ln. Zuvor arbeitete er in der Hotour Unternehmensberatung f\u00fcr Hotellerie und Touristik und im IFH-Institut f\u00fcr Hotelmanagement, wo er f\u00fcr nationale und internationale Hoteltests und Qualit\u00e4tstest in der Hotellerie verantwortlich war.<\/p>\n<p>In ruhiger Lage, am Rande des Siebengebirges liegt oberhalb von Bad Honnef\/Linz das Dorint Golf &amp; Spa Windhagen\/Siebengebirge. 116 Zimmer, eine gro\u00dfz\u00fcgige Suite und acht Studios laden zum Verweilen ein. Entspannung garantiert der 3.000 Quadratmeter gro\u00dfe Spa- &amp; Wellnessbereich. Mit ihrem italienisch-mediterran angehauchten Stil bildet die Hotelanlage ein zwangloses, inspirierendes Umfeld f\u00fcr Veranstaltungen aller Art. Auf 880 Quadratmetern stehen 14 Tagungsr\u00e4ume f\u00fcr Gespr\u00e4che, Tagungen, Feste, aber auch private Feierlichkeiten f\u00fcr bis zu 140 G\u00e4ste zur Verf\u00fcgung. Im Restaurant \u201eVilla Romantica\u201c werden die G\u00e4ste kulinarisch verw\u00f6hnt. Zudem stehen ihnen noch das \u00e0-la-carte-Restaurant \u201eIl Camino\u201c, der \u201eWintergarten\u201c, die gem\u00fctliche Kaminbar oder nach einem Aufenthalt im Spa-Bereich, die Poolbar zur Verf\u00fcgung.<\/p>\n<p><strong>\u00dcber Dorint<\/strong><br \/>\nDie Neue Dorint GmbH mit Sitz in K\u00f6ln betreibt mit der Marke Dorint Hotels &amp; Resorts euro-paweit 35 H\u00e4user. Rund 2.800 Mitarbeiter in Deutschland, in den Niederlanden, in der Schweiz, in Tschechien und Spanien leben eine herzliche und nat\u00fcrliche Gastlichkeit. Dorint Ho-tels &amp; Resorts geh\u00f6rt zu den f\u00fchrenden Hotel-ketten auf dem deutschen Markt.<\/p>\n<p>Quelle: Presse Dorint Hotels &amp; Resorts<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neuer Hoteldirektor des Dorint Golf &amp; Spa Windhagen\/Siebengebirge ist Rainer Sch\u00e4fer. Er will das Haus wieder als ein Hotel f\u00fcr Pferdefreunde etablieren. Windhagen\/K\u00f6ln \u2013 Kooperationen mit dem Reitsport, Engagement f\u00fcr Servicequalit\u00e4t und engere Kontakte zur Region: Mit viel Elan ist &hellip; <a href=\"https:\/\/www.tagungshotels-online.de\/blog\/2012\/07\/dorint-golf-spa-windhagensiebengebirge-golfen-reitsport-und-wellness-sind-die-trumpfe\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,7,8],"tags":[],"class_list":["post-2221","post","type-post","status-publish","format-standard","hentry","category-hotels","category-personalien","category-redaktion"],"_links":{"self":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/2221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/comments?post=2221"}],"version-history":[{"count":2,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/2221\/revisions"}],"predecessor-version":[{"id":2223,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/2221\/revisions\/2223"}],"wp:attachment":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/media?parent=2221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/categories?post=2221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/tags?post=2221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}