{"id":3434,"date":"2014-03-24T14:53:02","date_gmt":"2014-03-24T13:53:02","guid":{"rendered":"http:\/\/www.tagungshotels-online.de\/blog\/?p=3434"},"modified":"2014-03-24T14:53:02","modified_gmt":"2014-03-24T13:53:02","slug":"dorint-airport-hotel-zuerich-koelsche-toene-bei-hotel-eroeffnung","status":"publish","type":"post","link":"https:\/\/www.tagungshotels-online.de\/blog\/2014\/03\/dorint-airport-hotel-zuerich-koelsche-toene-bei-hotel-eroeffnung\/","title":{"rendered":"Dorint Airport-Hotel Z\u00fcrich: K\u00f6lsche T\u00f6ne bei Hotel-Er\u00f6ffnung"},"content":{"rendered":"<p><em><strong>Band\u00a0Cat\u00a0Ballou sorgt f\u00fcr ausgelassene Stimmung<\/strong><\/em><\/p>\n<p><strong>Z\u00fcrich, 24.03.2014 \u2013<\/strong> Der K\u00f6lner Dom stand einen Tag in Z\u00fcrich, garniert mit K\u00f6lsch vom Fass und musikalischer Unterst\u00fctzung durch die Band\u00a0Cat Ballou. Die singt ihre Lieder nat\u00fcrlich auch auf K\u00f6lsch. Mit einem herzlichen Augenzwinkern hie\u00df die K\u00f6lner Hotelgesellschaft\u00a0Dorint die G\u00e4ste der Er\u00f6ffnungsfeier des\u00a0\u00a0<a href=\"http:\/\/hotel-airport-zuerich.dorint.com\/\" target=\"_blank\">Dorint Airport-Hotel Z\u00fcrich<\/a> willkommen. Dementsprechend rheinisch stimmungsvoll verlief die Veranstaltung. Nach kurzen Gru\u00dfworten von\u00a0 Hoteldirektor Detlef F. Linder, Dr. Riccardo Boscardin, UBS Fund Management (Switzerland) AG, E.-Ulrich Schweitzer, Leiter Unternehmensentwicklung\u00a0Dorint Hotels &amp; Resorts, sowie Martin Sturzenegger, Direktor Z\u00fcrich Tourismus, wurde im ganzen Hotel gefeiert.<\/p>\n<div style=\"width: 550px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" \" alt=\"\" src=\"http:\/\/www.tagungshotels-online.de\/Pressebilder\/140324_Er%C3%B6ffnung_Z%C3%BCrich_mr.jpg\" width=\"540\" height=\"390\" \/><p class=\"wp-caption-text\">Hoteldirektor Detlef F. Linder, Dr. Riccardo Boscardin, UBS Fund Management (Switzerland) AG, E.-Ulrich Schweitzer, Leiter Unternehmensentwicklung Dorint Hotels &amp; Resorts, Martin Sturzenegger, Direktor Z\u00fcrich Tourismus (von links), bei der Er\u00f6ffnungsfeier des Dorint Airport-Hotel Z\u00fcrich.<br \/>Foto: Hans Weber &#8211; Dorint Hotels &amp; Resorts<\/p><\/div>\n<p>Nat\u00fcrlich durften die G\u00e4ste auch hinter die Kulissen des Hotels blicken. Bei der Hotelf\u00fchrung wurde nichts ausgelassen.\u00a0 Eines der Highlights des\u00a0Dorint Airport-Hotel Z\u00fcrich ist die Lobby. Sie befindet sich in der Mitte des Kreuzes, sozusagen im \u201eHerzen\u201c des Baus, und l\u00e4sst dem Besucher freien Blick in den Himmel. Das Besondere: In diesem Teil des Geb\u00e4udes fehlen die Zwischendecken. Die G\u00e4ste k\u00f6nnen also ungehindert f\u00fcnf Etagen nach oben schauen. Neben dem gro\u00dfartigen Raumgef\u00fchl ist das Kunstobjekt eines Schweizer Bob-Schlittens ein weiterer Blickfang. Es schwebt hoch \u00fcber den K\u00f6pfen der Besucher und ist ein Geschenk des Bauherren\u00a0Turintra AG an die\u00a0Dorint Hotels &amp; Resorts. <!--more--><\/p>\n<p>Zur Ausstattung geh\u00f6ren 235 moderne und klimatisierte Nichtraucherzimmer, davon 45 in der Superior-Kategorie und 13 Junior-Suiten, sieben der Zimmer sind behindertengerecht. Von den Superior-Zimmern im f\u00fcnften Stock kann man sogar auf die Start- und Landebahn des Flughafens blicken. Weitere Besonderheit sind vier\u00a0Syndicate Rooms. Diese Meeting-Suiten bestehen aus einem Hotelzimmer, das durch eine Verbindungst\u00fcr mit einem Besprechungsraum verbunden ist. \u00dcberhaupt finden Gesch\u00e4ftsreisende und Tagungsg\u00e4ste im\u00a0Dorint Airport-Hotel Z\u00fcrich optimale Bedingungen: Der gro\u00dfe Tagungsraum \u201eAirbus\u201c, die zwei Konferenz- und vier\u00a0Meetingr\u00e4ume sind alle tageslichtdurchflutet, verdunkelbar, klimatisiert und barrierefrei. Bis zu 180 Personen finden hier Platz.<\/p>\n<p>Kulinarisch verw\u00f6hnt werden die G\u00e4ste im Restaurant \u201eBasilico\u201c, das im modernen mediterranen Stil eingerichtet wurde. Auf gro\u00dfes Interesse st\u00f6\u00dft bereits vor der Hotel-Er\u00f6ffnung der Private-Dinner-Raum f\u00fcr bis zu zw\u00f6lf Personen. Hier kann sich w\u00e4hrend einer Veranstaltung die Gesch\u00e4ftsf\u00fchrung zu einem Lunch-Meeting zur\u00fcckziehen. Nat\u00fcrlich eignet sich der Raum auch f\u00fcr private Feierlichkeiten. Erg\u00e4nzt wird das gastronomische Angebot von einer gro\u00dfen Sommerterrasse mit Blick in den herrlichen Gartenbereich. Ebenfalls sehr\u00a0stylisch ist die Hotelbar mit gro\u00dfer Theke und gem\u00fctlichen Sitzgruppen.<\/p>\n<p>Das\u00a0Dorint Airport-Hotel Z\u00fcrich liegt zwei Kilometer vom Flughafen entfernt. Das moderne Vier-Sterne-Haus bietet 235 Nichtraucherzimmer, einen Saal, zwei Konferenz-, zwei\u00a0Meetingr\u00e4ume und vier\u00a0Syndicate-Rooms (Hotelzimmer mit Verbindungst\u00fcr zum Besprechungsraum). Das gastronomische Angebot umfasst das Restaurant \u201eBasilico\u201c, die Sommerterrasse mit Blick in den Garten sowie die Hotelbar mit gro\u00dfer Theke und gem\u00fctlichen Sitzgruppen. Als Ausgleich zum Stadtbummel in Z\u00fcrich oder dem Business-Meeting empfiehlt sich das hoteleigene Fitnesscenter mit modernen \u201eLifeFitness\u201c Sportger\u00e4ten. Erg\u00e4nzt wird das Hotelangebot durch etwa 90 Innen- und Au\u00dfenparkpl\u00e4tze, Taxistellpl\u00e4tze sowie einen Busparkplatz. Die verkehrsg\u00fcnstige Lage mit Autobahnanschluss in rund 500 Meter Entfernung, sehr guten Zugverbindungen sowie Anschl\u00fcssen an den \u00f6ffentlichen Nahverkehr sind weitere Standortvorteile.<\/p>\n<p>++++++++<br \/>\nDie Neue\u00a0Dorint GmbH mit Sitz in K\u00f6ln betreibt mit der Marke\u00a0Dorint Hotels &amp; Resorts europaweit 41 H\u00e4user. Rund 2.600 Mitarbeiter in Deutschland, in der Schweiz, in \u00d6sterreich, Tschechien und Spanien leben herzliche und nat\u00fcrliche Gastlichkeit.\u00a0Dorint Hotels &amp; Resorts geh\u00f6rt zu den f\u00fchrenden Hotelketten auf dem deutschen Markt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Band\u00a0Cat\u00a0Ballou sorgt f\u00fcr ausgelassene Stimmung Z\u00fcrich, 24.03.2014 \u2013 Der K\u00f6lner Dom stand einen Tag in Z\u00fcrich, garniert mit K\u00f6lsch vom Fass und musikalischer Unterst\u00fctzung durch die Band\u00a0Cat Ballou. Die singt ihre Lieder nat\u00fcrlich auch auf K\u00f6lsch. Mit einem herzlichen Augenzwinkern &hellip; <a href=\"https:\/\/www.tagungshotels-online.de\/blog\/2014\/03\/dorint-airport-hotel-zuerich-koelsche-toene-bei-hotel-eroeffnung\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8,12],"tags":[],"class_list":["post-3434","post","type-post","status-publish","format-standard","hentry","category-hotels","category-redaktion","category-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/3434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/comments?post=3434"}],"version-history":[{"count":1,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/3434\/revisions"}],"predecessor-version":[{"id":3435,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/posts\/3434\/revisions\/3435"}],"wp:attachment":[{"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/media?parent=3434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/categories?post=3434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tagungshotels-online.de\/blog\/wp-json\/wp\/v2\/tags?post=3434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}